{"id":526988,"date":"2019-09-28T16:52:21","date_gmt":"2019-09-28T14:52:21","guid":{"rendered":"https:\/\/modulor-records.com\/boutique\/uncategorized\/les-tigres-du-futur-collection-illusions-sonores-vol-3\/"},"modified":"2026-07-03T09:45:01","modified_gmt":"2026-07-03T07:45:01","slug":"les-tigres-du-futur-collection-illusions-sonores-vol-3","status":"publish","type":"product","link":"https:\/\/modulor-records.com\/en\/boutique\/les-tigres-du-futur-en\/les-tigres-du-futur-collection-illusions-sonores-vol-3\/","title":{"rendered":"Collection Illusions Sonores Vol. 3"},"content":{"rendered":"<p>Garage rock psych\u00e9d\u00e9lique, bande-son de film d\u2019horreur \u00e9rotique des ann\u00e9es 70 et second degr\u00e9, voici la recette du myst\u00e9rieux Jo-Bernard Castagneri appliqu\u00e9e ici \u00e0 la lettre par Les Tigres du Futur avec Collection Illusions Sonores Vol. 3 pour le label Music Fear Satan. On d\u00e9marre par un voyage initiatique en face A avec les 19 minutes du titre &#8220;Le Jour De La Col\u00e8re Astral&#8221;, v\u00e9ritable immersion spirituelle dans les profondeurs sid\u00e9rales du cosmos. En face B un nuage vivant de poussi\u00e8re stellaire assoiff\u00e9 d\u2019antimati\u00e8re d\u00e9vore une \u00e0 une les galaxies. Dans &#8220;Cosmos de Sang&#8221;, les sept Rishi, gardiens hindous de l\u2019humanit\u00e9, sont notre seul espoir face \u00e0 ce fl\u00e9au, mais les vieux ma\u00eetres cach\u00e9s parviendront-ils \u00e0 surmonter leur addiction au Purp, une nouvelle et terrifiante drogue de synth\u00e8se alt\u00e9rant la r\u00e9alit\u00e9 ? L\u2019aventure intersid\u00e9rante se termine avec le prog rock satanique de &#8220;L\u2019\u00c9toile de Satan&#8221;. Sur un satellite de Jupiter, l\u2019Ant\u00e9christ s\u2019incarne sous les traits d\u2019un protozoaire g\u00e9ant. D\u00e9jouant la vigilance du supercomputer Lomonosov-3, l\u2019amibe d\u00e9moniaque embarque \u00e0 bord d\u2019une sonde spatiale russe \u00e0 destination de la Terre. Un terrible jeu du chat et de la souris commence entre l\u2019IA et le Fils monocellulaire de Satan.<\/p>\n<ul>\n<li>A1. Le Jour De La Col\u00e8re Astrale (19&#8217;11)<\/li>\n<li>B1. Cosmos De Sang (09&#8217;00)<\/li>\n<li>B2. L\u2019\u00c9toile De Satan (07&#8217;57)<\/li>\n<\/ul>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/zmogT_1f71k\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Garage rock psych\u00e9d\u00e9lique, bande-son de film d\u2019horreur \u00e9rotique des ann\u00e9es 70 et second degr\u00e9, voici la recette du myst\u00e9rieux Jo-Bernard Castagneri appliqu\u00e9e ici \u00e0 la lettre par Les Tigres du Futur avec Collection Illusions Sonores Vol. 3 pour le label Music Fear Satan. On d\u00e9marre par un voyage initiatique en face A avec les 19&hellip;<\/p>\n","protected":false},"featured_media":522275,"template":"","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"product_cat":[8763],"product_tag":[6869],"class_list":{"0":"post-526988","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"label-music-fear-satan-en","7":"artist-les-tigres-du-futur-en","8":"product_cat-rock-inde-en","9":"product_tag-catalogue-en","10":"pa_format-1-lp-en","12":"first","13":"instock","14":"taxable","15":"shipping-taxable","16":"purchasable","17":"product-type-variable"},"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/modulor-records.com\/en\/wp-json\/wp\/v2\/product\/526988","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/modulor-records.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/modulor-records.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/modulor-records.com\/en\/wp-json\/wp\/v2\/media\/522275"}],"wp:attachment":[{"href":"https:\/\/modulor-records.com\/en\/wp-json\/wp\/v2\/media?parent=526988"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/modulor-records.com\/en\/wp-json\/wp\/v2\/product_cat?post=526988"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/modulor-records.com\/en\/wp-json\/wp\/v2\/product_tag?post=526988"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}