{"id":530132,"date":"2020-05-12T18:14:01","date_gmt":"2020-05-12T16:14:01","guid":{"rendered":"https:\/\/modulor-records.com\/unknown-artist\t\/kidbug\/"},"modified":"2026-07-03T09:44:48","modified_gmt":"2026-07-03T07:44:48","slug":"kidbug","status":"publish","type":"product","link":"https:\/\/modulor-records.com\/en\/boutique\/kidbug-en\/kidbug\/","title":{"rendered":"Kidbug"},"content":{"rendered":"<p>Kidbug se compose de Marina Tadic (Eerie Wanda), Adam Harding (Dumb Numbers), Thor Harris (Swans) et Bobb Bruno (Best Coast). N\u00e9s de la romance entre Marina et Adam, ils font, avec Thor et Bobb, ce qu&#8217;ils appellent du &#8220;cuddlebug sludge&#8221;, le r\u00e9sultat harmonieux de guitares grunge-gaze et de pop r\u00eaveuse. Les origines de Kidbug remontent \u00e0 d\u00e9cembre 2018. Alors qu&#8217;il \u00e9tait aux bureaux du label Joyful Noise Recordings \u00e0 Indianapolis pour leur f\u00eate annuelle de fin d&#8217;ann\u00e9e, Adam Harding a \u00e9t\u00e9 pr\u00e9sent\u00e9 pour la premi\u00e8re fois \u00e0 l&#8217;artiste d&#8217;origine croate et r\u00e9sidant aux Pays-Bas, Marina Tadic. Il se sont r\u00e9unis au studio Postal Recording \u00e0 Indianapolis pour enregistrer des chansons de No\u00ebl pour le label, et c&#8217;est \u00e0 partir de l\u00e0 que tout a commenc\u00e9. Cela a d\u00e9clench\u00e9 une s\u00e9rie de lettres d&#8217;amour musicales \u00e0 longue distance. Les premiers r\u00e9sultats \u00e9taient bruts, personnels et enti\u00e8rement sinc\u00e8res sur le plan \u00e9motionnel, avec une puret\u00e9 d&#8217;expression que Marina et Adam \u00e9taient d\u00e9sireux de pr\u00e9server. Pour parvenir \u00e0 une parfaite coh\u00e9sion, il fallait des \u00e9l\u00e9ments rythmiques puissants : Bobb Bruno de Best Coast a \u00e9t\u00e9 recrut\u00e9 pour la basse et la guitare secondaire, et Thor Harris pour la batterie et les percussions. Le l\u00e9gendaire Dale Crover, du groupe Melvins, fait une apparition sp\u00e9ciale derri\u00e8re les f\u00fbts sur &#8220;Dreamy&#8221;, le dernier morceau de l&#8217;album. Ce premier album \u00e9ponyme est aliment\u00e9 par un amour tr\u00e8s \u00e9lectrique et Kidbug esp\u00e8re parvenir \u00e0 transmettre cette \u00e9nergie magique aux auditeurs !<\/p>\n<ol>\n<li>Now Let&#8217;s Go To Sleep<\/li>\n<li>Lovesick<\/li>\n<li>Good Inside<\/li>\n<li>Moonglue<\/li>\n<li>Never<\/li>\n<li>Woozy<\/li>\n<li>Theme from Kidbug<\/li>\n<li>Together<\/li>\n<li>Stay<\/li>\n<li>Yesterdays<\/li>\n<li>Dreamy (feat. Dale Crover)<\/li>\n<\/ol>\n","protected":false},"excerpt":{"rendered":"<p>Kidbug se compose de Marina Tadic (Eerie Wanda), Adam Harding (Dumb Numbers), Thor Harris (Swans) et Bobb Bruno (Best Coast). N\u00e9s de la romance entre Marina et Adam, ils font, avec Thor et Bobb, ce qu&#8217;ils appellent du &#8220;cuddlebug sludge&#8221;, le r\u00e9sultat harmonieux de guitares grunge-gaze et de pop r\u00eaveuse. Les origines de Kidbug remontent&hellip;<\/p>\n","protected":false},"featured_media":529098,"template":"","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"product_cat":[8763],"product_tag":[6091,6869],"class_list":{"0":"post-530132","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"label-joyful-noise-en","7":"artist-kidbug-en","8":"product_cat-rock-inde-en","9":"product_tag-catalogue","10":"product_tag-catalogue-en","11":"pa_format-1-cd-en","12":"pa_format-1-lp-couleur-en","14":"first","15":"outofstock","16":"taxable","17":"shipping-taxable","18":"product-type-variable"},"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/modulor-records.com\/en\/wp-json\/wp\/v2\/product\/530132","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/modulor-records.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/modulor-records.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/modulor-records.com\/en\/wp-json\/wp\/v2\/media\/529098"}],"wp:attachment":[{"href":"https:\/\/modulor-records.com\/en\/wp-json\/wp\/v2\/media?parent=530132"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/modulor-records.com\/en\/wp-json\/wp\/v2\/product_cat?post=530132"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/modulor-records.com\/en\/wp-json\/wp\/v2\/product_tag?post=530132"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}