{"id":531830,"date":"2020-07-01T17:01:52","date_gmt":"2020-07-01T15:01:52","guid":{"rendered":"http:\/\/0"},"modified":"2026-08-27T09:36:02","modified_gmt":"2026-08-27T07:36:02","slug":"excellent-italian-greyhound","status":"publish","type":"product","link":"https:\/\/modulor-records.com\/fr\/boutique\/shellac\/excellent-italian-greyhound\/","title":{"rendered":"Excellent Italian Greyhound"},"content":{"rendered":"<p>Quatri\u00e8me album studio de Shellac, sorti en 2007 et 7 ans apr\u00e8s son pr\u00e9d\u00e9cesseur. M\u00eame si la plupart des titres de ce nouvel album sont alors jou\u00e9s en live depuis au moins 4 ans, disponibles en Peel Sessions ou en DVD (\u00ab\u00a0Steady As She Goes\u00a0\u00bb dans la s\u00e9rie Burn To Shine), on tient peut \u00eatre l\u00e0 le meilleur opus du groupe depuis le premier At Action Park de 1994, sans concession, ouvrant de nouvelles portes et chose importante pour ce groupe au statut si particulier, rassurant les fans de la bonne sant\u00e9 du trio Chicago. Ce qui frappe d&rsquo;ailleurs le plus sur cet Excellent Italian Greyhound c&rsquo;est cette notion de trio, Shellac s&rsquo;extirpe encore plus que d&rsquo;habitudes du clich\u00e9 &lsquo;groupe de Steve Albini&rsquo;, Trainer et Weston se faisant remarquer plus que Albini lui-m\u00eame au fil des titres. D\u00e8s \u00ab\u00a0The End Of Radio\u00a0\u00bb, ouverture grandiose et flippante, Albini d\u00e9clame son texte tout en retenue, alors que Weston l\u00e2che une ligne de basse ultra hypnotique et Trainer se lance dans des parties free rock de batterie&#8230; 8 minutes de tension incroyable. Une r\u00e9ussite totale. Derri\u00e8re le groupe enchaine avec deux titres plus classiques, mais toujours aussi efficaces et l\u2019album se cl\u00f4ture sur une bourrinerie hardcore b\u00eate et m\u00e9chante mais terriblement jouissive du nom de \u00ab\u00a0Spoke\u00a0\u00bb. Malgr\u00e9 sa courte dur\u00e9e de 42 minutes et comme on le disait plus haut son manque de titres vraiments inedits, Excellent Italian Greyhound remporte la mise en pr\u00e9sentant toutes les facettes de Shellac, sans chercher \u00e0 singer les albums pr\u00e9c\u00e9dents.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quatri\u00e8me album studio de Shellac, sorti en 2007 et 7 ans apr\u00e8s son pr\u00e9d\u00e9cesseur. M\u00eame si la plupart des titres de ce nouvel album sont alors jou\u00e9s en live depuis au moins 4 ans, disponibles en Peel Sessions ou en DVD (\u00ab\u00a0Steady As She Goes\u00a0\u00bb dans la s\u00e9rie Burn To Shine), on tient peut \u00eatre&hellip;<\/p>\n","protected":false},"featured_media":531705,"template":"","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"product_cat":[42],"product_tag":[6091],"class_list":{"0":"post-531830","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"label-touch-and-go-records","7":"artist-shellac","8":"product_cat-rock-inde","9":"product_tag-catalogue","10":"pa_format-1-cd","11":"pa_format-1-lp","13":"first","14":"outofstock","15":"taxable","16":"shipping-taxable","17":"product-type-variable"},"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/product\/531830","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/media\/531705"}],"wp:attachment":[{"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/media?parent=531830"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/product_cat?post=531830"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/product_tag?post=531830"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}