{"id":545783,"date":"2021-10-15T13:32:07","date_gmt":"2021-10-15T11:32:07","guid":{"rendered":"http:\/\/0"},"modified":"2026-07-15T11:52:35","modified_gmt":"2026-07-15T09:52:35","slug":"giant-guitar","status":"publish","type":"product","link":"https:\/\/modulor-records.com\/fr\/boutique\/omar-khorshid\/giant-guitar\/","title":{"rendered":"Giant + Guitar"},"content":{"rendered":"<p><span style=\"font-weight: 400;\"><strong>Wewantsounds<\/strong> r\u00e9\u00e9dite <em><strong>Giant + Guitar<\/strong><\/em> d&rsquo;<strong>Omar Khorshid<\/strong>, un album cl\u00e9 de la musique orientale, initialement sorti en 1974 sur le label <strong>Voice of Lebanon<\/strong> qui fait la part belle \u00e0 la guitare \u00e9lectrique en m\u00e9langeant des m\u00e9lodies orientales traditionnelle et des arrangements pop hypnotiques. La vie d&rsquo;<strong>Omar Khorshid<\/strong>, m\u00eame si elle fut courte (il meurt \u00e0 36 ans dans un accident de la route en 1981), a \u00e9t\u00e9 extraordinaire. Dot\u00e9 d&rsquo;un grand talent pour la musique, le musicien \u00e9gyptien devient dans les ann\u00e9es 60 l&rsquo;un des principaux guitaristes du monde arabe et accompagne les plus grandes stars de l\u2019\u00e9poque, Oum Kalthoum, Abdel Halim Hafez et Farid El Atrache parmi d\u2019autres. Pour \u00e9viter les troubles politiques de l&rsquo;\u00e9poque en \u00c9gypte et r\u00e9aliser ses ambitions artistiques, <strong>Khorshid<\/strong> s&rsquo;installe \u00e0 Beyrouth au Liban en 1973 et commence \u00e0 enregistrer une s\u00e9rie de superbes albums exp\u00e9rimentant avec la musique orientale. Il enregistre pour plusieurs labels dont Voice of Lebanon, l&rsquo;un des labels libanais phares de l&rsquo;\u00e9poque, et sort l\u2019album <em><strong>Giant + Guitar<\/strong><\/em> pour celui-ci en 1974. L\u2019album rencontre un vif succ\u00e8s dans le monde arabe, gr\u00e2ce notamment \u00e0 un son ample, enregistr\u00e9 dans le studio Polysound par l&rsquo;ing\u00e9nieur du son Nabil Moumtaz, une r\u00e9f\u00e9rence sur la sc\u00e8ne orientale. La pochette montre <strong>Khorshid<\/strong> sur sa moto dans une rue anim\u00e9e de Hamra, l&rsquo;un des quartiers les plus populaires de Beyrouth o\u00f9 il jouait la nuit, dans les clubs du quartier. L&rsquo;album est \u00e9galement sorti \u00e0 l&rsquo;international sous le titre Rhythms from the Orient avec une pochette diff\u00e9rente. La musique de <strong>Khorshid<\/strong> est \u00e0 la fois audacieuse et accessible, mettant en relief le son de guitare unique du musicien, accompagn\u00e9 ici par une formation r\u00e9duite m\u00e9langeant des arrangements traditionnels et modernes. Le morceau d&rsquo;ouverture, <strong>\u00ab\u00a0Rakset El Fadaa\u00a0\u00bb<\/strong>, compos\u00e9 par le musicien libanais Nour Al Mallah, est un parfait exemple du talent de <strong>Khorshid<\/strong>. Commen\u00e7ant par une longue intro hypnotique \u00e0 la guitare, il attaque ensuite la m\u00e9lodie, accompagn\u00e9 d\u2019un orgue groovy, de percussions orientales et les touches psych\u00e9d\u00e9liques d&rsquo;un synth\u00e9tiseur premi\u00e8re g\u00e9n\u00e9ration. L&rsquo;album continue sur sa lanc\u00e9e, comme le montre l\u2019interpr\u00e9tation du standard de Mohamed Abdel Wahab <strong>\u00ab\u00a0Leilet Hob\u00a0\u00bb<\/strong> popularis\u00e9 par Oum Kalthoum, qui voit Khorshid et ses musiciens changer de rythme plusieurs fois sur les huit minutes du titre. Un autre sommet de l&rsquo;album est sans aucun doute la propre composition de <strong>Khorshid<\/strong>, <strong>\u00ab\u00a0Taqassim Sanat Alfein\u00a0\u00bb<\/strong>, une longue improvisation \u00e0 la guitare accompagn\u00e9e de quelques touches de synth\u00e9. Gorg\u00e9 d\u2019innovations sonores, <em><strong>Giant + Guitar<\/strong><\/em> a repouss\u00e9 les limites de la musique orientale dans les ann\u00e9es 70. Il a gagn\u00e9 en stature au fil des d\u00e9cennies et est devenu un disque tr\u00e8s recherch\u00e9 par de nombreux DJ et collectionneurs du monde entier. L&rsquo;album a \u00e9t\u00e9 remasteris\u00e9 et ressort sous sa pochette d\u2019origine avec un encart de 2 pages contenant des notes de pochette par le <strong>DJ Ernesto Chahoud<\/strong>. La s\u00e9rie de r\u00e9\u00e9ditions de musique arabe du label <strong>Wewantsounds<\/strong> est supervis\u00e9e par Mario Choueiry de l&rsquo;Institut du Monde Arabe \u00e0 Paris. <\/span><\/p>\n<p>1. Raqset El Fadaa<br \/>\n2. Guitar El Chark<br \/>\n3. Takassim Sanat Alfeyn<br \/>\nB<br \/>\n4. Laylet Hob<br \/>\n5. Lama Bada Yatasana<br \/>\n6. Teletya Mahla Nourha<br \/>\n7. Ah Ya Zen<\/p>\n<p><iframe loading=\"lazy\" title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/EfzHZjUWb6c\" width=\"508\" height=\"285\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wewantsounds r\u00e9\u00e9dite Giant + Guitar d&rsquo;Omar Khorshid, un album cl\u00e9 de la musique orientale, initialement sorti en 1974 sur le label Voice of Lebanon qui fait la part belle \u00e0 la guitare \u00e9lectrique en m\u00e9langeant des m\u00e9lodies orientales traditionnelle et des arrangements pop hypnotiques. La vie d&rsquo;Omar Khorshid, m\u00eame si elle fut courte (il meurt&hellip;<\/p>\n","protected":false},"featured_media":545676,"template":"","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"product_cat":[33],"product_tag":[6091],"class_list":{"0":"post-545783","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"label-wewantsounds","7":"artist-omar-khorshid","8":"product_cat-musiques-du-monde","9":"product_tag-catalogue","10":"pa_format-1-lp","12":"first","13":"instock","14":"taxable","15":"shipping-taxable","16":"purchasable","17":"product-type-variable"},"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/product\/545783","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/media\/545676"}],"wp:attachment":[{"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/media?parent=545783"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/product_cat?post=545783"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/product_tag?post=545783"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}