{"id":554343,"date":"2022-08-29T18:24:22","date_gmt":"2022-08-29T16:24:22","guid":{"rendered":"http:\/\/0"},"modified":"2026-01-27T17:24:26","modified_gmt":"2026-01-27T16:24:26","slug":"the-spell","status":"publish","type":"product","link":"https:\/\/modulor-records.com\/fr\/boutique\/the-black-heart-procession\/the-spell\/","title":{"rendered":"The Spell"},"content":{"rendered":"<p>The Spell est une r\u00e9\u00e9dition limit\u00e9e du cinqui\u00e8me album du groupe de rock ind\u00e9 californien The Black Heart Procession, \u00e0 l\u2019occasion du quinzi\u00e8me anniversaire de sa sortie. Le groupe s\u2019est form\u00e9 \u00e0 San Diego en 1997, autour de Pall Jenkins (voix, guitares, synth\u00e9s, etc.) et Tobias Nathaniel (piano, guitare, orgue, etc.) de Three Mile Pilot. Les sorts peuvent \u00eatre jet\u00e9s sur une personne, une histoire d&rsquo;amour, une nation, etc ; ils enchantent et ils pi\u00e8gent, ils d\u00e9sorientent et ils leurrent. Ils sont au c\u0153ur de The Spell, \u00e0 la fois par les toiles qu&rsquo;ils tissent et le choc qui se produit lorsqu&rsquo;ils sont bris\u00e9s. Et il n&rsquo;y a pas de meilleur mot pour d\u00e9crire l&rsquo;ivresse effrayante du son de The Black Heart Procession. Leur son est celui que l\u2019on entend lorsque l&rsquo;on conduit de nuit \u00e0 travers l&rsquo;Ouest am\u00e9ricain. Comme les grands espaces, c&rsquo;est une musique qui sait \u00eatre \u00e0 la fois d\u00e9sol\u00e9e et luxuriante. Et elle sait que si la tristesse vous tire vers le bas, le m\u00e9contentement vous pousse vers l&rsquo; avant. C&rsquo;est pourquoi la procession ne s&rsquo;arr\u00eate jamais. Ici, le rythme 6\/8 d&rsquo;une chanson vous entra\u00eene dans une valse s\u00e9duisante et lunatique, et la seconde d&rsquo;apr\u00e8s, le violon et le piano \u00e9voquent l&rsquo;orchestre d&rsquo;un cabaret solitaire aux lumi\u00e8res tamis\u00e9es. Puis les cordes cessent de pleurer et se transforment en un rythme propulsif, et on file \u00e0 toute vitesse vers un cr\u00e9puscule cin\u00e9matographique. Il y a un \u00e9cho et une immensit\u00e9, un son assez grand pour remplir la nuit, plus grand que nature. Une bande-son pour ce trajet de minuit en solitaire, les villes fant\u00f4mes du c\u0153ur revenant \u00e0 la vie.<\/p>\n<ol>\n<li>Tangled<\/li>\n<li>The Spell<\/li>\n<li>Not Just Words<\/li>\n<li>The Letter<\/li>\n<li>The Replacement<\/li>\n<li>Return To Burn<\/li>\n<li>GPS<\/li>\n<li>The Waiter #5<\/li>\n<li>Places<\/li>\n<li>The Fix<\/li>\n<li>To Bring You Back<\/li>\n<\/ol>\n","protected":false},"excerpt":{"rendered":"<p>The Spell est une r\u00e9\u00e9dition limit\u00e9e du cinqui\u00e8me album du groupe de rock ind\u00e9 californien The Black Heart Procession, \u00e0 l\u2019occasion du quinzi\u00e8me anniversaire de sa sortie. Le groupe s\u2019est form\u00e9 \u00e0 San Diego en 1997, autour de Pall Jenkins (voix, guitares, synth\u00e9s, etc.) et Tobias Nathaniel (piano, guitare, orgue, etc.) de Three Mile Pilot.&hellip;<\/p>\n","protected":false},"featured_media":554111,"template":"","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"product_cat":[42],"product_tag":[6091],"class_list":{"0":"post-554343","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"label-touch-and-go-records","7":"artist-the-black-heart-procession","8":"product_cat-rock-inde","9":"product_tag-catalogue","10":"pa_format-1-lp-couleur","12":"first","13":"outofstock","14":"taxable","15":"shipping-taxable","16":"product-type-variable"},"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/product\/554343","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/media\/554111"}],"wp:attachment":[{"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/media?parent=554343"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/product_cat?post=554343"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/product_tag?post=554343"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}