{"id":557762,"date":"2023-02-07T09:30:17","date_gmt":"2023-02-07T08:30:17","guid":{"rendered":"http:\/\/0"},"modified":"2026-07-15T11:51:56","modified_gmt":"2026-07-15T09:51:56","slug":"operation-doomsday","status":"publish","type":"product","link":"https:\/\/modulor-records.com\/fr\/boutique\/mf-doom\/operation-doomsday\/","title":{"rendered":"Operation: Doomsday"},"content":{"rendered":"<p>Sous son myst\u00e9rieux masque de m\u00e9tal, MF DOOM dissimule le cachet dont sont faites les l\u00e9gendes de l&rsquo;underground. Apr\u00e8s que l&rsquo;album Black Bastards de son premier groupe, KMD, ait \u00e9t\u00e9 mis au placard par Elektra en 1994, et que son fr\u00e8re de sang Subroc &#8211; la moiti\u00e9 du duo rap &#8211; d\u00e9c\u00e8de, Zev Love X, le leader survivant, s&rsquo;est lentement transform\u00e9 en MC super-m\u00e9chant connu sous le nom de MF DOOM, et le monde du rap s&rsquo;en porte mieux. La sortie en 1999 de Operation: Doomsday marque les d\u00e9buts officiels de MF DOOM, r\u00e9introduisant un personnage myst\u00e9rieux qui deviendra bient\u00f4t l&rsquo;une des plus grandes voix du rap underground. Avec ses 19 titres, Operation: Doomsday r\u00e9v\u00e8le la confluence du pass\u00e9 tragique de DOOM, de ses int\u00e9r\u00eats personnels et de sa cr\u00e9ativit\u00e9 audacieuse. Ses rimes intelligentes et ses sch\u00e9mas remarquables se d\u00e9tachent du paysage, et tous les sons qu&rsquo;il touche &#8211; des g\u00e9n\u00e9riques de dessins anim\u00e9s \u00e0 la soul des ann\u00e9es 80, en passant par les classiques du rap et autres &#8211; sont r\u00e9interpr\u00e9t\u00e9s en quelque chose de tout \u00e0 fait nouveau et surr\u00e9aliste. Des d\u00e9cennies plus tard, MF DOOM est toujours c\u00e9l\u00e9br\u00e9 pour toutes les facettes de son travail et de son influence. Face \u00e0 la trag\u00e9die, DOOM a r\u00e9infiltr\u00e9 le rap game \u00e0 sa mani\u00e8re et a cr\u00e9\u00e9 un classique culte instantan\u00e9. Operation: Doomsday montre \u00e0 quel point parier sur soi contre vents et mar\u00e9es peut \u00eatre puissant. Pressage sur double vinyle<\/p>\n<ol>\n<li>The Time We Faced Doom (Skit)<\/li>\n<li>Doomsday<\/li>\n<li>Rhymes Like Dimes<\/li>\n<li>The Finest<\/li>\n<li>Back In The Days (Skit)<\/li>\n<li>Go With The Flow<\/li>\n<li>Tick, Tick&#8230;<\/li>\n<li>Red And Gold<\/li>\n<li>The Hands Of Doom (Skit)<\/li>\n<li>Who You Think I Am?<\/li>\n<li>Doom, Are You Awake? (Skit)<\/li>\n<li>Hey!<\/li>\n<li>Operation: Greenbacks<\/li>\n<li>The Mic<\/li>\n<li>The Mystery Of Doom (Skit)<\/li>\n<li>Dead Bent<\/li>\n<li>Gas Drawls<\/li>\n<li>?<\/li>\n<li>Hero v.s. Villain (Epilogue)<\/li>\n<\/ol>\n","protected":false},"excerpt":{"rendered":"<p>Sous son myst\u00e9rieux masque de m\u00e9tal, MF DOOM dissimule le cachet dont sont faites les l\u00e9gendes de l&rsquo;underground. Apr\u00e8s que l&rsquo;album Black Bastards de son premier groupe, KMD, ait \u00e9t\u00e9 mis au placard par Elektra en 1994, et que son fr\u00e8re de sang Subroc &#8211; la moiti\u00e9 du duo rap &#8211; d\u00e9c\u00e8de, Zev Love X,&hellip;<\/p>\n","protected":false},"featured_media":557707,"template":"","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"product_cat":[23],"product_tag":[6091],"class_list":{"0":"post-557762","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"label-rhymesayers-entertainment","7":"artist-mf-doom","8":"product_cat-rap-us","9":"product_tag-catalogue","10":"pa_format-1-cd","11":"pa_format-2-lp","12":"pa_format-k7","14":"first","15":"instock","16":"taxable","17":"shipping-taxable","18":"purchasable","19":"product-type-variable"},"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/product\/557762","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/media\/557707"}],"wp:attachment":[{"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/media?parent=557762"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/product_cat?post=557762"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/product_tag?post=557762"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}