{"id":558645,"date":"2023-02-14T17:40:46","date_gmt":"2023-02-14T16:40:46","guid":{"rendered":"http:\/\/0"},"modified":"2026-01-27T17:03:43","modified_gmt":"2026-01-27T16:03:43","slug":"psalms-2","status":"publish","type":"product","link":"https:\/\/modulor-records.com\/fr\/boutique\/david-grubbs\/psalms-2\/","title":{"rendered":"Psalms"},"content":{"rendered":"<p>En 2022, la pand\u00e9mie semblait reculer au point que les artistes pouvaient \u00e0 nouveau travailler ensemble, main dans la main. Ainsi, comme une sorte de suite \u00e0 son coffret d&rsquo;artiste en r\u00e9sidence de 2020 chez Joyful Noise, Kramer a examin\u00e9 l&rsquo;id\u00e9e d&rsquo;un coffret vinyle en \u00e9dition limit\u00e9e c\u00e9l\u00e9brant les joies de la collaboration. Elle lui a sembl\u00e9 encore meilleure en tant que projet de six EP sur 45 tours. Les paysages sans fronti\u00e8res de l&rsquo;art audio, temp\u00e9r\u00e9s par l&rsquo;imagination des artistes choisis, puis projet\u00e9s contre les myriades infinies de myst\u00e8res entre ces anneaux \u00e9ternels qui tournent. Voici donc le deuxi\u00e8me EP du projet, Psalms, avec David Grubbs (Codeine). Ce projet ne changera pas le monde, mais les mots et la musique qui s&rsquo;\u00e9chappent de ces sillons expriment avec pr\u00e9cision l&rsquo;amour vers\u00e9 dans les fondations de Nocturnes (avec Britta Phillips), Psalms (avec David Grubbs), Preludes (avec Eerie Wanda), Elegies (avec Jad Fair et Danielson), Laments (avec Paul Leary) et Hymns (avec Rob Crow). Pressage sur 45 tours<\/p>\n<ol>\n<li>Lendrick Muir Bible Study Weekend<\/li>\n<li>Congress of Poodles<\/li>\n<\/ol>\n","protected":false},"excerpt":{"rendered":"<p>En 2022, la pand\u00e9mie semblait reculer au point que les artistes pouvaient \u00e0 nouveau travailler ensemble, main dans la main. Ainsi, comme une sorte de suite \u00e0 son coffret d&rsquo;artiste en r\u00e9sidence de 2020 chez Joyful Noise, Kramer a examin\u00e9 l&rsquo;id\u00e9e d&rsquo;un coffret vinyle en \u00e9dition limit\u00e9e c\u00e9l\u00e9brant les joies de la collaboration. Elle lui&hellip;<\/p>\n","protected":false},"featured_media":558585,"template":"","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"product_cat":[42],"product_tag":[6091],"class_list":{"0":"post-558645","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"label-shimmy-disc","7":"artist-david-grubbs","8":"artist-kramer","9":"product_cat-rock-inde","10":"product_tag-catalogue","11":"pa_format-1-45t","13":"first","14":"outofstock","15":"taxable","16":"shipping-taxable","17":"product-type-variable"},"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/product\/558645","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/media\/558585"}],"wp:attachment":[{"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/media?parent=558645"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/product_cat?post=558645"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/product_tag?post=558645"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}