{"id":558653,"date":"2023-02-14T17:27:05","date_gmt":"2023-02-14T16:27:05","guid":{"rendered":"http:\/\/0"},"modified":"2026-08-27T09:32:38","modified_gmt":"2026-08-27T07:32:38","slug":"wede-harer-guzo","status":"publish","type":"product","link":"https:\/\/modulor-records.com\/fr\/boutique\/hailu-mergia-and-dahlak-band\/wede-harer-guzo\/","title":{"rendered":"Wede Harer Guzo"},"content":{"rendered":"<p>Wede Harer Guzo de Hailu Mergia &amp; Dahlak Band est la troisi\u00e8me sortie du clavi\u00e9riste et accord\u00e9oniste culte \u00e9thiopien sur Awesome Tapes From Africa. En 1978, la vie nocturne d&rsquo;Addis-Abeba, en Ethiopie, est confront\u00e9e \u00e0 un couvre-feu, interdisant aux citoyens de circuler dans les rues la nuit. Mais cela n&#8217;emp\u00eache pas les gens de danser et de faire la f\u00eate toute la nuit. Les groupes jouent du soir jusqu&rsquo;au lever du jour et le public reste dans les clubs jusqu&rsquo;\u00e0 ce que le couvre-feu soit lev\u00e9 au matin ! Hailu Mergia, un des principaux artistes de l&rsquo;\u00e2ge d&rsquo;or musical d\u2019Addis-Abeba, pr\u00e9pare la suite de son album Tche Belew avec le c\u00e9l\u00e8bre Walias Band. Mais ce groupe, r\u00e9sident du Hilton hotel, est occup\u00e9 \u00e0 enregistrer des cassettes avec diff\u00e9rents chanteurs. Mergia, d\u00e9sireux de faire un enregistrement de ses arrangements instrumentaux, fait appel au groupe de l&rsquo;h\u00f4tel Ghion, bo\u00eete de nuit populaire, le Dahlak Band. Ensemble, ils r\u00e9alisent cette bande, Wede Harer Guzo, pendant les r\u00e9p\u00e9titions du groupe au club. Le Dahlak Band, avec ses jams principalement soul et amhariques, s&rsquo;adresse \u00e0 un public local plus jeune que celui que Mergia a avec le Walias Band, compos\u00e9 de riches \u00c9thiopiens, de diplomates \u00e9trangers et de seniors de l&rsquo;\u00e9tranger. Mergia sort Wede Harer Guzo (\u00ab\u00a0Voyage \u00e0 Harer\u00a0\u00bb, une ville de l&rsquo;est de l&rsquo;\u00c9thiopie) en 1978 avec Sheba Music Shop, et la copie sur cassette est la seule source que le label a pu utiliser, en nettoyant les couches de sifflement, de flottement et de fr\u00e9quences d\u00e9form\u00e9es. M\u00eame s\u2019il reste quelques r\u00e9sidus sonores des conditions d\u2019enregistrement, cette r\u00e9\u00e9dition d\u2019un classique ultra-rare, pour la premi\u00e8re fois disponible hors Ethiopie, capture l&rsquo;ambiance inimitable du groupe !<\/p>\n<ol>\n<li>Embuwa Bey Lamitu<\/li>\n<li>Sintayehu<\/li>\n<li>Bati Bati<\/li>\n<li>Migibima Moltual<\/li>\n<li>Yene Nesh Wey (Amalele)<\/li>\n<li>Wede Harer Guzo<\/li>\n<li>Yemanesh Ayinama<\/li>\n<li>Almaz Eyasebkush<\/li>\n<li>Anchin Kfu Ayinkash<\/li>\n<li>Minlbelesh<\/li>\n<\/ol>\n","protected":false},"excerpt":{"rendered":"<p>Wede Harer Guzo de Hailu Mergia &amp; Dahlak Band est la troisi\u00e8me sortie du clavi\u00e9riste et accord\u00e9oniste culte \u00e9thiopien sur Awesome Tapes From Africa. En 1978, la vie nocturne d&rsquo;Addis-Abeba, en Ethiopie, est confront\u00e9e \u00e0 un couvre-feu, interdisant aux citoyens de circuler dans les rues la nuit. Mais cela n&#8217;emp\u00eache pas les gens de danser&hellip;<\/p>\n","protected":false},"featured_media":558606,"template":"","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"product_cat":[33],"product_tag":[6091],"class_list":{"0":"post-558653","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"label-awesome-tapes-from-africa","7":"artist-hailu-mergia-and-dahlak-band","8":"product_cat-musiques-du-monde","9":"product_tag-catalogue","10":"pa_format-2-lp","11":"pa_format-k7","13":"first","14":"instock","15":"taxable","16":"shipping-taxable","17":"purchasable","18":"product-type-variable"},"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/product\/558653","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/media\/558606"}],"wp:attachment":[{"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/media?parent=558653"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/product_cat?post=558653"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/product_tag?post=558653"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}