{"id":571198,"date":"2023-12-05T16:53:16","date_gmt":"2023-12-05T15:53:16","guid":{"rendered":"http:\/\/0"},"modified":"2026-07-05T23:58:10","modified_gmt":"2026-07-05T21:58:10","slug":"moons-milk","status":"publish","type":"product","link":"https:\/\/modulor-records.com\/fr\/boutique\/coil\/moons-milk\/","title":{"rendered":"Moon&rsquo;s Milk"},"content":{"rendered":"<p>D&rsquo;abord sorti en compilation en 2002, Moon&rsquo;s Milk (in Four Phases) est une suite de quatre EPs que Coil a produit de mani\u00e8re saisonni\u00e8re via leur label Eskaton en 1998. Le line-up de ces sessions \u00e9tait compos\u00e9 de John Balance, Peter \u00ab\u00a0Sleazy\u00a0\u00bb Christopherson, Drew McDowall et William Breeze. Enregistr\u00e9 principalement dans leur home studio de Londres, \u00e0 la veille d&rsquo;un d\u00e9m\u00e9nagement d\u00e9finitif dans la petite ville baln\u00e9aire de Weston-Super-Mare, ce recueil a longtemps \u00e9t\u00e9 consid\u00e9r\u00e9 comme une pi\u00e8ce ma\u00eetresse de la discographie du groupe, mais il n&rsquo;a jamais \u00e9t\u00e9 officiellement \u00e9dit\u00e9 en vinyle. Organis\u00e9 s\u00e9quentiellement en hommage aux \u00e9quinoxes et solstices, Moon&rsquo;s Milk capture Coil \u00e0 un carrefour r\u00e9v\u00e9lateur, se penchant plus profond\u00e9ment sur l&rsquo;improvisation, la spontan\u00e9it\u00e9 et le design sonore. Le coffret Dais comprend l&rsquo;int\u00e9gralit\u00e9 du rare CD-R bonus Moon&rsquo;s Milk \/ 2019 Threshold Archives Copal, qui inclut trois collaborations avec Thighpaulsandra. Une fois de plus, Coil confirme l&rsquo;immensit\u00e9 de son alchimie d\u00e9routante et infinie. Du post-industriel au post-tout, c&rsquo;est un art sans attaches, dans la nature sauvage de sa propre conception.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>D&rsquo;abord sorti en compilation en 2002, Moon&rsquo;s Milk (in Four Phases) est une suite de quatre EPs que Coil a produit de mani\u00e8re saisonni\u00e8re via leur label Eskaton en 1998. Le line-up de ces sessions \u00e9tait compos\u00e9 de John Balance, Peter \u00ab\u00a0Sleazy\u00a0\u00bb Christopherson, Drew McDowall et William Breeze. Enregistr\u00e9 principalement dans leur home studio de&hellip;<\/p>\n","protected":false},"featured_media":571084,"template":"","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"product_cat":[42],"product_tag":[6091],"class_list":{"0":"post-571198","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"label-dais-records","7":"artist-coil","8":"product_cat-rock-inde","9":"product_tag-catalogue","10":"pa_format-3-lp-transparent-rouge","11":"pa_format-3-lp-transparent","12":"pa_format-2-cd","13":"pa_format-3-lp","15":"first","16":"instock","17":"taxable","18":"shipping-taxable","19":"purchasable","20":"product-type-variable"},"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/product\/571198","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/media\/571084"}],"wp:attachment":[{"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/media?parent=571198"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/product_cat?post=571198"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/product_tag?post=571198"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}