{"id":578974,"date":"2024-09-06T15:12:03","date_gmt":"2024-09-06T13:12:03","guid":{"rendered":"http:\/\/0"},"modified":"2026-06-23T14:57:32","modified_gmt":"2026-06-23T12:57:32","slug":"tweez-35th-anniversary-edition","status":"publish","type":"product","link":"https:\/\/modulor-records.com\/fr\/boutique\/slint\/tweez-35th-anniversary-edition\/","title":{"rendered":"Tweez (35Th Anniversary Edition)"},"content":{"rendered":"<p>Le premier album de Slint, enregistr\u00e9 par Steve Albini et paru en 1989, a \u00e9t\u00e9 remasteris\u00e9 par Bob Weston \u00e0 partir des bandes originales analogiques. Cette version pr\u00e9sente, sur le deuxi\u00e8me LP, l\u2019album enti\u00e8rement remix\u00e9 \u00e0 partir des masters originaux, de la fa\u00e7on dont Ethan Buckler (bassiste sur Tweez) l\u2019a toujours voulu, s\u2019\u00e9tant plaint pendant des ann\u00e9es de la production de Steve Albini pour leur premier disque. Buckler a remis \u00e0 l&rsquo;ing\u00e9nieur une copie d&rsquo;une cassette de r\u00e9p\u00e9tition de Slint datant d&rsquo;avant Tweez en guise de guide pour le remixage. Pressage sur double vinyle blanc 180 grammes num\u00e9rot\u00e9s \u00e0 la main. Notes de Steve Albini et Ethan Buckler<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le premier album de Slint, enregistr\u00e9 par Steve Albini et paru en 1989, a \u00e9t\u00e9 remasteris\u00e9 par Bob Weston \u00e0 partir des bandes originales analogiques. Cette version pr\u00e9sente, sur le deuxi\u00e8me LP, l\u2019album enti\u00e8rement remix\u00e9 \u00e0 partir des masters originaux, de la fa\u00e7on dont Ethan Buckler (bassiste sur Tweez) l\u2019a toujours voulu, s\u2019\u00e9tant plaint pendant&hellip;<\/p>\n","protected":false},"featured_media":578886,"template":"","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"product_cat":[7819,42],"product_tag":[6091],"class_list":{"0":"post-578974","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"label-touch-and-go-records","7":"artist-slint","8":"product_cat-empty","9":"product_cat-rock-inde","10":"product_tag-catalogue","11":"pa_format-2-lp-blanc","13":"first","14":"instock","15":"taxable","16":"shipping-taxable","17":"purchasable","18":"product-type-variable"},"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/product\/578974","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/media\/578886"}],"wp:attachment":[{"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/media?parent=578974"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/product_cat?post=578974"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/product_tag?post=578974"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}