{"id":579182,"date":"2024-09-12T17:13:21","date_gmt":"2024-09-12T15:13:21","guid":{"rendered":"http:\/\/0"},"modified":"2026-07-15T11:51:03","modified_gmt":"2026-07-15T09:51:03","slug":"recomecar","status":"publish","type":"product","link":"https:\/\/modulor-records.com\/fr\/boutique\/tim-bernardes\/recomecar\/","title":{"rendered":"Recome\u00e7ar"},"content":{"rendered":"<p>Tim Bernardes est un chanteur, auteur-compositeur, musicien et producteur nomm\u00e9 deux fois aux Latin Grammy. Il s&rsquo;est impos\u00e9 comme l&rsquo;un des talents musicaux br\u00e9siliens les plus remarquables de sa g\u00e9n\u00e9ration et comme un ph\u00e9nom\u00e8ne mondial. Nombreux sont ceux qui ont d\u00e9couvert la voix exceptionnelle et les paroles m\u00e9taphysiques de Tim Bernardes gr\u00e2ce \u00e0 son album Mil Coisas Invis\u00edveis, sorti en 2022, mais c&rsquo;est avec son premier album, Recome\u00e7ar, que Tim Bernardes a accueilli les auditeurs dans son univers sonore singulier : chaleureux, intime, \u00e9motionnellement r\u00e9sonnant, gu\u00e9risseur. L&rsquo;album a \u00e9t\u00e9 principalement \u00e9crit pendant la tourn\u00e9e de son groupe de rock ind\u00e9 tropicalia, O Terno, et est sorti en 2017. Maintenant largement disponible pour la premi\u00e8re fois, Recome\u00e7ar est une collection de r\u00e9flexions intimes sur la nature du chagrin d&rsquo;amour et du deuil.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tim Bernardes est un chanteur, auteur-compositeur, musicien et producteur nomm\u00e9 deux fois aux Latin Grammy. Il s&rsquo;est impos\u00e9 comme l&rsquo;un des talents musicaux br\u00e9siliens les plus remarquables de sa g\u00e9n\u00e9ration et comme un ph\u00e9nom\u00e8ne mondial. Nombreux sont ceux qui ont d\u00e9couvert la voix exceptionnelle et les paroles m\u00e9taphysiques de Tim Bernardes gr\u00e2ce \u00e0 son album&hellip;<\/p>\n","protected":false},"featured_media":578717,"template":"","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"product_cat":[7819,42],"product_tag":[6091],"class_list":{"0":"post-579182","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"label-psychic-hotline","7":"artist-tim-bernardes","8":"product_cat-empty","9":"product_cat-rock-inde","10":"product_tag-catalogue","11":"pa_format-1-cd","12":"pa_format-1-lp","14":"first","15":"instock","16":"taxable","17":"shipping-taxable","18":"purchasable","19":"product-type-variable"},"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/product\/579182","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/media\/578717"}],"wp:attachment":[{"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/media?parent=579182"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/product_cat?post=579182"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/product_tag?post=579182"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}