{"id":589818,"date":"2025-09-04T12:56:18","date_gmt":"2025-09-04T10:56:18","guid":{"rendered":"http:\/\/0"},"modified":"2026-01-27T10:04:00","modified_gmt":"2026-01-27T09:04:00","slug":"ratsnake","status":"publish","type":"product","link":"https:\/\/modulor-records.com\/fr\/boutique\/chloe-kim\/ratsnake\/","title":{"rendered":"Ratsnake"},"content":{"rendered":"<p>\u00c9lev\u00e9e en Cor\u00e9e et aujourd\u2019hui install\u00e9e \u00e0 Sydney, la percussionniste Chloe Kim s\u2019affirme comme une voix singuli\u00e8re de la batterie contemporaine, m\u00ealant improvisation audacieuse, clart\u00e9 compositionnelle et profondeur interculturelle. Ratsnake marque son entr\u00e9e ambitieuse dans le canon des albums de batterie solo, alliant puissance visc\u00e9rale, pr\u00e9cision et imagination. Kim s\u2019est fait remarquer \u00e0 l\u2019international en 2023 gr\u00e2ce \u00e0 sa performance solo de 100 heures sur 10 jours, qualifi\u00e9e d\u2019\u00ab hercul\u00e9enne \u00bb par The Guardian. Sur Ratsnake, elle canalise cette endurance et cette vision dans un travail studio profond\u00e9ment personnel, explorant tout le potentiel sonore de la batterie et la consid\u00e9rant comme un instrument \u00e0 la fois m\u00e9lodique et sculptural. Le titre de l\u2019album fait r\u00e9f\u00e9rence \u00e0 un r\u00eave que la m\u00e8re de Kim a eu avant sa naissance, le ratsnake\u2014symbole cor\u00e9en de r\u00e9silience, transformation et chance rare\u2014qui traverse l\u2019album \u00e0 travers ses motifs rythmiques complexes et \u00e9l\u00e9gants. Chaque morceau r\u00e9v\u00e8le un aspect de son langage solo, des cycles rythmiques \u00e9tendus aux textures in\u00e9dites pour ses performances live, comme dans \u201cThe First Gift\u201d ou \u201cBirth Dream\u201d. Produit et enregistr\u00e9 par Randall Dunn, Annea Lockwood et Kali Malone, Ratsnake restitue la richesse et la finesse de sa phrasing dynamique. Ce premier album puissant et nuanc\u00e9 red\u00e9finit les possibilit\u00e9s de la percussion solo tout en affirmant la personnalit\u00e9 unique de Kim.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c9lev\u00e9e en Cor\u00e9e et aujourd\u2019hui install\u00e9e \u00e0 Sydney, la percussionniste Chloe Kim s\u2019affirme comme une voix singuli\u00e8re de la batterie contemporaine, m\u00ealant improvisation audacieuse, clart\u00e9 compositionnelle et profondeur interculturelle. Ratsnake marque son entr\u00e9e ambitieuse dans le canon des albums de batterie solo, alliant puissance visc\u00e9rale, pr\u00e9cision et imagination. Kim s\u2019est fait remarquer \u00e0 l\u2019international en&hellip;<\/p>\n","protected":false},"featured_media":589741,"template":"","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"product_cat":[7819,28],"product_tag":[6091],"class_list":{"0":"post-589818","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"label-kou-records","7":"artist-chloe-kim","8":"product_cat-empty","9":"product_cat-jazz","10":"product_tag-catalogue","11":"pa_format-1-lp","13":"first","14":"instock","15":"taxable","16":"shipping-taxable","17":"purchasable","18":"product-type-variable"},"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/product\/589818","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/media\/589741"}],"wp:attachment":[{"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/media?parent=589818"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/product_cat?post=589818"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/product_tag?post=589818"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}