{"id":592555,"date":"2025-12-18T14:06:26","date_gmt":"2025-12-18T13:06:26","guid":{"rendered":"http:\/\/0"},"modified":"2026-07-15T11:49:58","modified_gmt":"2026-07-15T09:49:58","slug":"dialddar","status":"publish","type":"product","link":"https:\/\/modulor-records.com\/fr\/boutique\/oum\/dialddar\/","title":{"rendered":"Dialddar"},"content":{"rendered":"<p>Originaire de Casablanca, Oum est une b\u00e2tisseuse de chansons. Enracin\u00e9e dans les rythmes complexes du Maroc et grande m\u00e9lodiste, elle a fa\u00e7onn\u00e9 au fil des ann\u00e9es une signature unique : des chansons nourries de th\u00e8mes sensuels, port\u00e9es par une voix \u00e0 la fois puissante et caressante. Si elle emprunte parfois aux langages du jazz, de la soul ou de la transe, Oum \u00e9chappe \u00e0 toute classification. Sa musique est celle d\u2019une artiste singuli\u00e8re, libre et universelle. Artiste engag\u00e9e, Oum d\u00e9fend la libert\u00e9, les droits des femmes et des minorit\u00e9s, ainsi qu\u2019une vision \u00e9cologique et humaniste du monde. Ambassadrice de bonne volont\u00e9 de l\u2019ONUSIDA, elle fait de son art un espace de r\u00e9sistance et de partage, o\u00f9 la spiritualit\u00e9 et la po\u00e9sie s\u2019\u00e9l\u00e8vent comme une force de vie. Avec Dialddar (\u201cfait maison\u201d), Oum ose un geste radical : composer un album sans cordes ni vents, en s\u2019appuyant uniquement sur la voix et les percussions. Un choix qui constitue \u00e0 la fois un d\u00e9fi technique et un manifeste artistique. Les percussions utilis\u00e9es sont pour la plupart fabriqu\u00e9es artisanalement \u00e0 Marrakech. Leur accordage, sensible aux variations de temp\u00e9rature et d\u2019humidit\u00e9, rend chaque enregistrement fragile, vivant, changeant. C\u2019est pr\u00e9cis\u00e9ment cette dimension organique que Oum a souhait\u00e9 pr\u00e9server : une musique qui respire, qui \u00e9chappe au contr\u00f4le, et qui trouve sa justesse dans l\u2019instant. Avec Dialddar, Oum poursuit sa qu\u00eate d\u2019une musique universelle, enracin\u00e9e et visionnaire, qui invite \u00e0 l\u2019\u00e9coute sensible du monde.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Originaire de Casablanca, Oum est une b\u00e2tisseuse de chansons. Enracin\u00e9e dans les rythmes complexes du Maroc et grande m\u00e9lodiste, elle a fa\u00e7onn\u00e9 au fil des ann\u00e9es une signature unique : des chansons nourries de th\u00e8mes sensuels, port\u00e9es par une voix \u00e0 la fois puissante et caressante. Si elle emprunte parfois aux langages du jazz, de&hellip;<\/p>\n","protected":false},"featured_media":592518,"template":"","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"product_cat":[7819,348,33],"product_tag":[6091,930],"class_list":{"0":"post-592555","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"label-ternaire","7":"artist-oum","8":"product_cat-empty","9":"product_cat-moyen-orient","10":"product_cat-musiques-du-monde","11":"product_tag-catalogue","12":"product_tag-la-selection","13":"pa_format-1-cd-1-livre","14":"pa_format-1-cd","15":"pa_format-1-lp-blanc","17":"first","18":"instock","19":"taxable","20":"shipping-taxable","21":"purchasable","22":"product-type-variable"},"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/product\/592555","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/media\/592518"}],"wp:attachment":[{"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/media?parent=592555"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/product_cat?post=592555"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/product_tag?post=592555"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}