{"id":594788,"date":"2026-01-15T12:43:39","date_gmt":"2026-01-15T11:43:39","guid":{"rendered":"http:\/\/0"},"modified":"2026-07-03T09:41:55","modified_gmt":"2026-07-03T07:41:55","slug":"fading-forward","status":"publish","type":"product","link":"https:\/\/modulor-records.com\/fr\/boutique\/les-imprimes\/fading-forward\/","title":{"rendered":"Fading Forward"},"content":{"rendered":"<p><span data-sheets-root=\"1\">Big Crown Records est fier de pr\u00e9senter le deuxi\u00e8me album des Imprim\u00e9s, Fading Forward. Men\u00e9 par Morten Martens, multi-instrumentiste et producteur autodidacte, cet album explore la mortalit\u00e9, l&rsquo;\u00e9vasion et une multitude d&rsquo;exp\u00e9riences li\u00e9es \u00e0 l&rsquo;amour. Martens a fait forte impression avec son premier album R\u00eaverie, sorti en 2023 et acclam\u00e9 par la critique. Depuis, il a fid\u00e9lis\u00e9 un public aussi diversifi\u00e9 que ses influences musicales. Il m\u00e9lange des sonorit\u00e9s soul des ann\u00e9es 60 et 70 avec des arrangements doo-wop; puise son \u00e9nergie rythmique dans le hip-hop; et enveloppe le tout d&rsquo;un chant alternatif des ann\u00e9es 90 et 2000. Mais ce sont surtout ses textes, l&rsquo;\u00e9motion qu&rsquo;il y met et son interpr\u00e9tation qui donnent \u00e0 sa musique toute sa coh\u00e9rence et le distinguent de ses pairs. L&rsquo;\u00e9criture, d&rsquo;une \u00e9nergie communicative et d&rsquo;une sensibilit\u00e9 pop, est ex\u00e9cut\u00e9e avec une \u00e9l\u00e9gance et un go\u00fbt exquis, conf\u00e9rant aux Imprim\u00e9s ce charme imm\u00e9diat et rare qui ne fait que s&rsquo;intensifier \u00e0 chaque \u00e9coute. Originaire de Kristiansand, en Norv\u00e8ge, Morten joue de presque tous les instruments sur Fading Forward, a produit et arrang\u00e9 l&rsquo;album, et bien s\u00fbr, chant\u00e9. \u00ab C&rsquo;est de la soul, mais je n&rsquo;ai pas vraiment la voix d&rsquo;un artiste soul \u00bb, explique-t-il humblement. \u00ab Je le fais \u00e0 ma fa\u00e7on, avec mon propre style. \u00bb Dans la petite ville de Kristanland, en Norv\u00e8ge, un immense talent a longtemps v\u00e9cu dans l&rsquo;ombre. Sa signature chez le label new-yorkais Big Crown Records a incit\u00e9 Morten Martens \u00e0 partager sa propre musique. Le succ\u00e8s de son premier album, R\u00eaverie, l&rsquo;a propuls\u00e9 sur sc\u00e8ne, l&rsquo;encourageant \u00e0 repousser les limites de son art. Des sommets pleinement r\u00e9v\u00e9l\u00e9s dans Fading Forward.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Big Crown Records est fier de pr\u00e9senter le deuxi\u00e8me album des Imprim\u00e9s, Fading Forward. Men\u00e9 par Morten Martens, multi-instrumentiste et producteur autodidacte, cet album explore la mortalit\u00e9, l&rsquo;\u00e9vasion et une multitude d&rsquo;exp\u00e9riences li\u00e9es \u00e0 l&rsquo;amour. Martens a fait forte impression avec son premier album R\u00eaverie, sorti en 2023 et acclam\u00e9 par la critique. Depuis, il&hellip;<\/p>\n","protected":false},"featured_media":594640,"template":"","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"product_cat":[7819,49],"product_tag":[6091],"class_list":{"0":"post-594788","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"label-big-crown-records","7":"artist-les-imprimes","8":"product_cat-empty","9":"product_cat-soul-funk","10":"product_tag-catalogue","11":"pa_format-1-cd","12":"pa_format-1-lp","13":"pa_format-1-lp-vert","14":"pa_format-k7","16":"first","17":"instock","18":"taxable","19":"shipping-taxable","20":"purchasable","21":"product-type-variable"},"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/product\/594788","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/media\/594640"}],"wp:attachment":[{"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/media?parent=594788"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/product_cat?post=594788"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/product_tag?post=594788"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}