{"id":598378,"date":"2026-04-02T16:03:36","date_gmt":"2026-04-02T14:03:36","guid":{"rendered":"https:\/\/modulor-records.com\/fr\/boutique\/henry-fraser\/pneuma\/"},"modified":"2026-06-18T12:40:21","modified_gmt":"2026-06-18T10:40:21","slug":"pneuma","status":"publish","type":"product","link":"https:\/\/modulor-records.com\/fr\/boutique\/henry-fraser\/pneuma\/","title":{"rendered":"Pneuma"},"content":{"rendered":"<p><span data-sheets-root=\"1\">Pneuma est un cycle de huit compositions du contrebassiste et compositeur Henry Fraser, paru chez Kou Records. Explorant le souffle, la r\u00e9sonance et la relation \u00e9volutive entre forme et improvisation, Fraser con\u00e7oit sa pratique solo comme une collaboration avec l&rsquo;instrument lui-m\u00eame. Il travaille directement avec la mat\u00e9rialit\u00e9 et les propri\u00e9t\u00e9s acoustiques de la contrebasse, laissant \u00e9merger simultan\u00e9ment son, espace et structure par une \u00e9coute attentive. Enregistr\u00e9, mix\u00e9 et coproduit par Randall Dunn (Sunn O))), Thurston Moore) et Ben Greenberg (Uniform, Marc Ribot), l&rsquo;album enrichit le langage musical solo de Fraser gr\u00e2ce \u00e0 un registre m\u00e9lodique \u00e9tendu, des textures superpos\u00e9es et des interventions en studio finement cisel\u00e9es. Puisant \u00e0 la fois dans des motifs pr\u00e9-compos\u00e9s et dans des improvisations, Pneuma se d\u00e9ploie en une s\u00e9rie de mouvements concis, chacun donnant forme \u00e0 une id\u00e9e rythmique ou harmonique distincte tout en contribuant \u00e0 une forme continue d&rsquo;ensemble. Captur\u00e9 avec une attention particuli\u00e8re port\u00e9e \u00e0 la dynamique naturelle et aux d\u00e9tails spatiaux, l&rsquo;enregistrement pr\u00e9serve la pleine pr\u00e9sence physique de l&rsquo;instrument, mettant en avant la r\u00e9sonance, les harmoniques et les subtiles micro-mouvements de la basse. Certaines pi\u00e8ces sont construites \u00e0 partir de multiples performances superpos\u00e9es, \u00e9largissant consid\u00e9rablement l&rsquo;\u00e9chelle et la palette expressive de la musique. Il en r\u00e9sulte une exp\u00e9rience d&rsquo;\u00e9coute \u00e0 la fois intime et immersive : une musique acoustique qui se r\u00e9v\u00e8le simultan\u00e9ment tactile et ample. Pneuma t\u00e9moigne de la clart\u00e9 artistique de Fraser, r\u00e9affirmant son engagement envers une composition ax\u00e9e sur le processus et une pratique sonore attentive.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pneuma est un cycle de huit compositions du contrebassiste et compositeur Henry Fraser, paru chez Kou Records. Explorant le souffle, la r\u00e9sonance et la relation \u00e9volutive entre forme et improvisation, Fraser con\u00e7oit sa pratique solo comme une collaboration avec l&rsquo;instrument lui-m\u00eame. Il travaille directement avec la mat\u00e9rialit\u00e9 et les propri\u00e9t\u00e9s acoustiques de la contrebasse, laissant&hellip;<\/p>\n","protected":false},"featured_media":598282,"template":"","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"product_cat":[7819,28],"product_tag":[6091],"class_list":{"0":"post-598378","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"label-kou-records","7":"artist-henry-fraser","8":"product_cat-empty","9":"product_cat-jazz","10":"product_tag-catalogue","11":"pa_format-1-lp","13":"first","14":"instock","15":"taxable","16":"shipping-taxable","17":"purchasable","18":"product-type-variable"},"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/product\/598378","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/media\/598282"}],"wp:attachment":[{"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/media?parent=598378"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/product_cat?post=598378"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/product_tag?post=598378"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}