{"id":598875,"date":"2026-04-23T13:38:55","date_gmt":"2026-04-23T11:38:55","guid":{"rendered":"https:\/\/modulor-records.com\/fr\/boutique\/bonne-nuit\/crier-vomir-pleurer\/"},"modified":"2026-08-27T09:26:47","modified_gmt":"2026-08-27T07:26:47","slug":"crier-vomir-pleurer","status":"publish","type":"product","link":"https:\/\/modulor-records.com\/fr\/boutique\/bonne-nuit\/crier-vomir-pleurer\/","title":{"rendered":"Crier Vomir Pleurer"},"content":{"rendered":"<p><span data-sheets-root=\"1\">Avec cet EP, Bonne Nuit pose les bases de son identit\u00e9 : une pop \u00e9lectronique frontale, tendue et fi\u00e9vreuse, pens\u00e9e comme une derni\u00e8re danse avant la fin du monde. Port\u00e9 par des synth\u00e9s satur\u00e9s, une batterie obs\u00e9dante et une \u00e9nergie brute, le duo transforme l\u2019angoisse de notre \u00e9poque en transe collective. Chaque chanson capture un fragment de leur univers : l\u2019urgence, la rage, l\u2019exc\u00e8s, la fuite, l&rsquo;amour. Entre tension punk, refrains obsessionnels et chansons d\u2019amour sans filtre, cet EP condense l\u2019essence de Bonne Nuit : des morceaux abrasifs, g\u00e9n\u00e9rationnels et f\u00e9d\u00e9rateurs, faits pour se perdre, se d\u00e9fouler et rester vivants jusqu\u2019au bout de la nuit.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Avec cet EP, Bonne Nuit pose les bases de son identit\u00e9 : une pop \u00e9lectronique frontale, tendue et fi\u00e9vreuse, pens\u00e9e comme une derni\u00e8re danse avant la fin du monde. Port\u00e9 par des synth\u00e9s satur\u00e9s, une batterie obs\u00e9dante et une \u00e9nergie brute, le duo transforme l\u2019angoisse de notre \u00e9poque en transe collective. Chaque chanson capture un&hellip;<\/p>\n","protected":false},"featured_media":598826,"template":"","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"product_cat":[7819,269],"product_tag":[6091],"class_list":{"0":"post-598875","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"label-bonjour-","7":"artist-bonne-nuit","8":"product_cat-empty","9":"product_cat-pop-rock","10":"product_tag-catalogue","11":"pa_format-1-m45t","13":"first","14":"instock","15":"taxable","16":"shipping-taxable","17":"purchasable","18":"product-type-variable"},"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/product\/598875","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/media\/598826"}],"wp:attachment":[{"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/media?parent=598875"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/product_cat?post=598875"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/product_tag?post=598875"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}