{"id":601429,"date":"2026-06-11T13:26:58","date_gmt":"2026-06-11T11:26:58","guid":{"rendered":"https:\/\/modulor-records.com\/fr\/boutique\/elanor-moss\/the-knife-the-needle\/"},"modified":"2026-09-01T11:17:13","modified_gmt":"2026-09-01T09:17:13","slug":"the-knife-the-needle","status":"publish","type":"product","link":"https:\/\/modulor-records.com\/fr\/boutique\/elanor-moss\/the-knife-the-needle\/","title":{"rendered":"The Knife, The Needle"},"content":{"rendered":"<p><span data-sheets-root=\"1\">L&rsquo;enregistrement de son premier album, The Knife, The Needle, a \u00e9t\u00e9 un processus de gu\u00e9rison pour Elanor Moss apr\u00e8s deux EP remarqu\u00e9s, Citrus (2022) et Cosmic (2023). D\u00e9\u00e7ue par une p\u00e9riode d&rsquo;exp\u00e9rimentation sonore trop charg\u00e9e, l&rsquo;artiste a choisi de revenir \u00e0 ses racines folk contemporaines en privil\u00e9giant la lenteur et l&rsquo;introspection. En s&rsquo;appuyant sur la th\u00e9rapie et l&rsquo;utilisation d&rsquo;un magn\u00e9tophone quatre pistes, elle a explor\u00e9 son histoire familiale et la complexit\u00e9 des relations humaines. \u00ab\u00a0Sarah Waiting in the Car\u00a0\u00bb donne le ton, avec le jeu de guitare d\u00e9licat et contemplatif d\u2019Elanor et les subtiles interventions de l\u2019ensemble de Matthew Herd &#8211; Marcus Hamblett (cor), Jool Owen (cor), Andrew Stuart-Buttle (violon), Reid Jenkins (violon), Linus Fenton (contrebasse) et Herd (saxophone) &#8211; qui embellissent ses paroles d\u2019une gravit\u00e9 d\u00e9chirante, tandis que le r\u00e9cit passe d\u2019une rencontre dans un bar aux cons\u00e9quences d\u2019une relation abusive, la douceur se muant en violence. \u00c0 travers des morceaux comme \u00ab\u00a0Fixer\u00a0\u00bb, Elanor examine comment l&rsquo;amour peut tour \u00e0 tour blesser ou r\u00e9parer, transformant symboliquement le couteau en aiguille pour recoudre les plaies. Apr\u00e8s avoir abandonn\u00e9 une premi\u00e8re version enregistr\u00e9e \u00e0 New York, elle a choisi de r\u00e9enregistrer l&rsquo;int\u00e9gralit\u00e9 de l&rsquo;\u0153uvre dans les Highlands \u00e9cossais avec le producteur Pete Miles. Ce choix risqu\u00e9 a permis de faire \u00e9merger un son plus calme, \u00e9trange et typiquement anglais, r\u00e9v\u00e9lant toute l&rsquo;\u00e9tendue de son talent. Finalement, The Knife, The Needle s&rsquo;impose comme une \u0153uvre d&rsquo;une grande vuln\u00e9rabilit\u00e9 o\u00f9 chaque blessure partag\u00e9e se transforme en une po\u00e9sie lumineuse port\u00e9e par la voix et la guitare de l&rsquo;artiste.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;enregistrement de son premier album, The Knife, The Needle, a \u00e9t\u00e9 un processus de gu\u00e9rison pour Elanor Moss apr\u00e8s deux EP remarqu\u00e9s, Citrus (2022) et Cosmic (2023). D\u00e9\u00e7ue par une p\u00e9riode d&rsquo;exp\u00e9rimentation sonore trop charg\u00e9e, l&rsquo;artiste a choisi de revenir \u00e0 ses racines folk contemporaines en privil\u00e9giant la lenteur et l&rsquo;introspection. En s&rsquo;appuyant sur la&hellip;<\/p>\n","protected":false},"featured_media":601490,"template":"","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"product_cat":[7819,42],"product_tag":[6091],"class_list":{"0":"post-601429","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"label-merge-records","7":"artist-elanor-moss","8":"product_cat-empty","9":"product_cat-rock-inde","10":"product_tag-catalogue","11":"pa_format-1-cd","12":"pa_format-1-violet","14":"first","15":"instock","16":"taxable","17":"shipping-taxable","18":"purchasable","19":"product-type-variable"},"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/product\/601429","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/media\/601490"}],"wp:attachment":[{"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/media?parent=601429"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/product_cat?post=601429"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/product_tag?post=601429"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}