{"id":602042,"date":"2026-07-16T12:36:21","date_gmt":"2026-07-16T10:36:21","guid":{"rendered":"https:\/\/modulor-records.com\/fr\/boutique\/matu-miranda\/apuama\/"},"modified":"2026-08-10T17:26:11","modified_gmt":"2026-08-10T15:26:11","slug":"apuama","status":"publish","type":"product","link":"https:\/\/modulor-records.com\/fr\/boutique\/matu-miranda\/apuama\/","title":{"rendered":"Apuama"},"content":{"rendered":"<p><span data-sheets-root=\"1\">Depuis l&rsquo;enfance, Matu Miranda a grandi dans le mouvement. Changer de maison, de ville, d&rsquo;\u00e9cole ou d&rsquo;horizon a fa\u00e7onn\u00e9 son regard sur le monde et nourri une \u0153uvre profond\u00e9ment travers\u00e9e par les notions de d\u00e9placement, de transformation et d\u2019appartenance. Avec APUAMA, son deuxi\u00e8me album, le chanteur, compositeur et guitariste br\u00e9silien livre son travail le plus personnel \u00e0 ce jour : une collection de chansons qui explorent la mani\u00e8re dont chacun construit sa propre id\u00e9e du foyer au fil des rencontres, des d\u00e9parts et des retours. Port\u00e9 par une \u00e9criture sensible et une production organique, APUAMA navigue entre MPB contemporaine, folk tropicale, po\u00e9sie populaire et influences acoustiques br\u00e9siliennes. D&rsquo;une chanson \u00e0 l&rsquo;autre, Matu dessine un itin\u00e9raire intime o\u00f9 la saudade n&rsquo;est jamais synonyme d&rsquo;immobilit\u00e9, mais devient au contraire une force qui pousse \u00e0 avancer, \u00e0 d\u00e9couvrir et \u00e0 cr\u00e9er du lien. Des paysages lumineux de \u00ab\u00a0\u00c9 Bom Voltar\u00a0\u00bb aux questionnements existentiels de \u00ab\u00a0O Que Ser\u00e1 de N\u00f3s\u00a0\u00bb, en passant par le manifeste po\u00e9tique qu&rsquo;est \u00ab\u00a0Apuama\u00a0\u00bb, l&rsquo;album raconte l&rsquo;histoire d&rsquo;un artiste qui apprend \u00e0 faire de chaque lieu travers\u00e9 une forme de maison. L&rsquo;album b\u00e9n\u00e9ficie \u00e9galement de collaborations remarqu\u00e9es avec deux des voix les plus singuli\u00e8res de la nouvelle sc\u00e8ne br\u00e9silienne. La chanteuse et compositrice Josyara apporte sa sensibilit\u00e9 \u00e0 \u00ab\u00a0C\u00e9u Azulzin\u00a0\u00bb, tandis que Chico Chico rejoint Matu sur \u00ab\u00a0Est\u00e9tica da Fome\u00a0\u00bb, un titre inspir\u00e9 par les grandes r\u00e9flexions culturelles et sociales br\u00e9siliennes. Ces rencontres prolongent l&rsquo;esprit collectif qui traverse tout le disque et t\u00e9moignent du dialogue permanent de Matu Miranda avec sa g\u00e9n\u00e9ration artistique. La r\u00e9alisation sonore a \u00e9t\u00e9 confi\u00e9e \u00e0 Leo Marques, producteur, ing\u00e9nieur du son et musicien reconnu comme l&rsquo;une des figures majeures de la sc\u00e8ne ind\u00e9pendante br\u00e9silienne. Leo Marques a notamment remport\u00e9 un Latin Grammy Award pour sa participation \u00e0 l&rsquo;album Sim Sim Sim du groupe Bala Desejo, l&rsquo;un des disques les plus marquants de la musique br\u00e9silienne r\u00e9cente. Son approche offre \u00e0 APUAMA un son chaleureux, vivant et intemporel, laissant respirer les chansons et mettant en valeur la richesse des arrangements acoustiques. Plus qu&rsquo;un simple recueil de chansons, APUAMA est un carnet de voyage int\u00e9rieur. Un disque qui parle de mouvement, de m\u00e9moire, de nature et de transmission, et qui rappelle qu&rsquo;au-del\u00e0 des fronti\u00e8res, des distances et des absences, il existe toujours un endroit o\u00f9 l&rsquo;on peut se sentir chez soi. <\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Depuis l&rsquo;enfance, Matu Miranda a grandi dans le mouvement. Changer de maison, de ville, d&rsquo;\u00e9cole ou d&rsquo;horizon a fa\u00e7onn\u00e9 son regard sur le monde et nourri une \u0153uvre profond\u00e9ment travers\u00e9e par les notions de d\u00e9placement, de transformation et d\u2019appartenance. Avec APUAMA, son deuxi\u00e8me album, le chanteur, compositeur et guitariste br\u00e9silien livre son travail le plus&hellip;<\/p>\n","protected":false},"featured_media":602776,"template":"","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"product_cat":[7819,33],"product_tag":[6091],"class_list":{"0":"post-602042","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"label-pineapple-french-pop","7":"artist-matu-miranda","8":"product_cat-empty","9":"product_cat-musiques-du-monde","10":"product_tag-catalogue","11":"pa_format-1-cd","12":"pa_format-1-lp","14":"first","15":"instock","16":"taxable","17":"shipping-taxable","18":"purchasable","19":"product-type-variable"},"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/product\/602042","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/media\/602776"}],"wp:attachment":[{"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/media?parent=602042"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/product_cat?post=602042"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/modulor-records.com\/fr\/wp-json\/wp\/v2\/product_tag?post=602042"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}